{"id":112224,"date":"2025-05-15T09:00:00","date_gmt":"2022-01-01T08:02:00","guid":{"rendered":"https:\/\/piradosbrand.com\/product\/camiseta-nuevo-estilo-no-face-no-case-negra\/"},"modified":"2026-02-15T12:07:10","modified_gmt":"2026-02-15T10:07:10","slug":"no-face-no-case-camiseta-new-style-negro","status":"publish","type":"product","link":"https:\/\/piradosbrand.com\/es\/producto\/no-face-no-case-camiseta-new-style-negro\/","title":{"rendered":"\u00abNO FACE NO CASE\u00bb -CAMISETA NEW STYLE, NEGRO"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p data-start=\"0\" data-end=\"210\">\u201cNo Face No Case 2.0\u201d es una camiseta de l\u00edneas limpias con actitud, creada para el uso diario. El tejido c\u00f3modo, flexible y que mantiene su forma la hace perfecta para la calle, el gimnasio o un estilo casual.<\/p>\n<p data-start=\"212\" data-end=\"237\">Simple. Directa. Visible.<\/p>\n<p data-start=\"239\" data-end=\"373\">El producto est\u00e1 en stock en nuestra tienda insignia y listo para env\u00edo. <strong>Los pedidos se despachan en un m\u00e1ximo de 2 d\u00edas laborables.<\/strong><\/p>\n<p data-start=\"375\" data-end=\"476\">Solo 1000 unidades producidas en todo el mundo.<br data-start=\"422\" data-end=\"425\" \/>Si tu talla est\u00e1 agotada, este producto desaparece.<\/p>\n<p data-start=\"478\" data-end=\"553\" data-is-last-node=\"\" data-is-only-node=\"\">Calidad: 92% algod\u00f3n peinado \/ 8% elastano<br data-start=\"520\" data-end=\"523\" \/>Peso: 170 g\/m\u00b2<br data-start=\"537\" data-end=\"540\" \/>Single jersey<\/p>\n","protected":false},"featured_media":134764,"template":"","meta":[],"product_brand":[],"product_cat":[858,856,842,840,846,836],"product_tag":[798,799,793,1540,1537,1539,1538,1535,1541,1536],"class_list":{"0":"post-112224","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-nuevos-productos","7":"product_cat-camisas-polos-y-tirantes","8":"product_cat-camisetas-y-tops","9":"product_cat-hombres","10":"product_cat-mujeres","11":"product_cat-todos-los-productos","12":"product_tag-camiseta-es","13":"product_tag-camiseta-es-2","14":"product_tag-camiseta","15":"product_tag-hip-hop-tee-es","16":"product_tag-logo-t-sark-es","17":"product_tag-must-t-sark-es","18":"product_tag-oversized-t-shirt-es","19":"product_tag-streetwear-t-sark-es","20":"product_tag-tattoo-shirt-es","21":"product_tag-urban-style-tee-es","23":"first","24":"instock","25":"taxable","26":"shipping-taxable","27":"purchasable","28":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/piradosbrand.com\/es\/wp-json\/wp\/v2\/product\/112224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/piradosbrand.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/piradosbrand.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/piradosbrand.com\/es\/wp-json\/wp\/v2\/media\/134764"}],"wp:attachment":[{"href":"https:\/\/piradosbrand.com\/es\/wp-json\/wp\/v2\/media?parent=112224"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/piradosbrand.com\/es\/wp-json\/wp\/v2\/product_brand?post=112224"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/piradosbrand.com\/es\/wp-json\/wp\/v2\/product_cat?post=112224"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/piradosbrand.com\/es\/wp-json\/wp\/v2\/product_tag?post=112224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}